{"id":1661,"date":"2026-05-08T13:52:49","date_gmt":"2026-05-08T13:52:49","guid":{"rendered":"http:\/\/sokadohi.cyon.site\/produkt\/asr-3300\/"},"modified":"2026-07-15T18:53:16","modified_gmt":"2026-07-15T18:53:16","slug":"asr-3300","status":"publish","type":"product","link":"https:\/\/ccontrols.shop\/de\/product\/asr-3300\/","title":{"rendered":"ASR-3300"},"content":{"rendered":"<h1>GW INSTEK ASR-3300&nbsp;<\/h1>\n<p>- Programmierbare AC-DC-Stromquelle, 3000 VA, USB + LAN + RS-232 + GPIB<\/p>\n<p>Der ASR-3300 ist eine AC\/DC-Stromquelle, die sich durch eine kurze Anstiegs- und Abfallzeit der Gleichspannung (100 \u00b5s) auszeichnet. Ausgangsleistung: 3 kVA Der ASR-3300 kann sowohl im Wechselstrom- als auch im Gleichstrombetrieb die Nennleistung bereitstellen. Es stehen neun Betriebsmodi f\u00fcr den ASR-3300 zur Verf\u00fcgung, darunter: <br \/>&nbsp;1. Wechselstrom-Ausgabemodus (AC-INT-Modus)<br \/>&nbsp;2. Gleichstrom-Ausgabemodus (DC-INT-Modus)<br \/>&nbsp;3. AC\/DC-Ausgabemodus (AC+DC-INT-Modus)<br \/>&nbsp;4. Modus f\u00fcr externe Wechselstromsignalquelle (AC-EXT-Modus)<br \/>&nbsp;5. Modus f\u00fcr externe AC\/DC-Signalquelle (AC+DC-EXT-Modus)<br \/>&nbsp;6. Modus zur \u00dcberlagerung eines externen Wechselstromsignals (AC-ADD-Modus)<br \/>&nbsp;7. Modus zur \u00dcberlagerung externer AC\/DC-Signale (AC+DC-ADD-Modus)<br \/>&nbsp;8. Synchronisationsmodus \u00fcber externes Wechselstromsignal (AC-SYNC-Modus)<br \/>&nbsp;9. Synchronisationsmodus f\u00fcr externe AC\/DC-Signale (AC+DC-SYNC-Modus)<\/p>\n<p>Der ASR-3300 eignet sich ideal f\u00fcr die Entwicklung von Bordladeger\u00e4ten, Server-Stromversorgungen, LED-Modulen, Wechselstrommotoren, Wechselstroml\u00fcftern, USV-Anlagen und verschiedenen elektronischen Bauteilen sowie f\u00fcr Testanwendungen bei elektrischen Ausr\u00fcstungen im Automobilbereich und bei Haushaltsger\u00e4ten.<\/p>\n<p>Wichtigste Merkmale:<br \/>- Nennleistung: Wechselstrom 0400 Vrms, Gleichstrom 0570 V<br \/>- Ausgangsfrequenz bis zu 999,9 Hz<br \/>- Gleichstromausgang (100 % der Nennleistung)<br \/>- Messgr\u00f6\u00dfen: Vrms, Vavg, Vpeak, Irms, IpkH, Iavg, Ipeak, P, S, Q, PF, CF<br \/>- Analyse der Spannungs- und Stromoberwellen (THDv, THDi)<br \/>- Fernerkundungsf\u00e4higkeiten<br \/>- OCP, OPP, OTP, Erkennung von Wechselstromausf\u00e4llen und Alarm bei L\u00fcfterausfall<br \/>- Unterst\u00fctzung der Funktion Beliebige Wellenform\"<br \/>- Ausgangsleistung: 3 kVA<br \/>- Individuell einstellbarer Phasenwinkel f\u00fcr das Ein- und Ausschalten des Ausgangs<br \/>- Sequenz- und Simulationsfunktion (bis zu 10 S\u00e4tze)<br \/>- Schnittstellen: USB, LAN, RS-232, GPIB<br \/>- Integrierte externe Steuer-E\/A und externe Signaleing\u00e4nge<br \/>- Integrierte Steuerung des Ausgangsrelais<br \/>- Speicherfunktion (bis zu 10 S\u00e4tze)<br \/>- Integrierter Webserver<\/p>\n<hr>\n<h3>Warum sollten Sie sich f\u00fcr den ASR-3300 entscheiden?<\/h3>\n<p>Dieses Ger\u00e4t wurde entwickelt, um in anspruchsvollen Umgebungen den h\u00f6chsten Standards hinsichtlich Genauigkeit und Zuverl\u00e4ssigkeit gerecht zu werden. Ob in der Forschung und Entwicklung, der Qualit\u00e4tskontrolle oder bei Produktionstests es bietet die konstante Leistung, auf die Fachleute vertrauen. F\u00fcr technische Beratung und weitere Informationen wenden Sie sich bitte noch heute an unser Expertenteam. <\/p>\n<p><a href=\"https:\/\/ccontrols.shop\/wp-content\/uploads\/2026\/05\/GWInstek_ASR-3000-series_Datasheet_Ccontrols.pdf\">GWInstek_ASR-3000-Serie_Datenblatt_Steuerungen<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"custom-attribute-values-only\" style=\"font-size: 15px; font-weight: 500; line-height: 1.4; color: #333;\">AC\/DC Source, 3000 VA, 0-350 V, 1-999 Hz, LAN, Gro\u00dfes LCD, Simulation<\/div>\n","protected":false},"featured_media":41810,"comment_status":"closed","ping_status":"open","template":"","meta":{"content-type":""},"product_brand":[1265],"product_cat":[256],"product_tag":[],"class_list":["post-1661","product","type-product","status-publish","has-post-thumbnail","product_brand-gw-instek","product_cat-stromversorgungen","pa_display-groses-lcd","pa_freq-1-999-hz","pa_function-simulation","pa_interface-lan-usb","pa_power-6762","pa_power-type-ac-dc-source","pa_power-unit-va","pa_voltage-0-350-v","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author","","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"builder_content":"","_links":{"self":[{"href":"https:\/\/ccontrols.shop\/de\/wp-json\/wp\/v2\/product\/1661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccontrols.shop\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ccontrols.shop\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ccontrols.shop\/de\/wp-json\/wp\/v2\/comments?post=1661"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccontrols.shop\/de\/wp-json\/wp\/v2\/media\/41810"}],"wp:attachment":[{"href":"https:\/\/ccontrols.shop\/de\/wp-json\/wp\/v2\/media?parent=1661"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ccontrols.shop\/de\/wp-json\/wp\/v2\/product_brand?post=1661"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ccontrols.shop\/de\/wp-json\/wp\/v2\/product_cat?post=1661"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ccontrols.shop\/de\/wp-json\/wp\/v2\/product_tag?post=1661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}