{"id":2894,"date":"2026-05-08T14:16:16","date_gmt":"2026-05-08T14:16:16","guid":{"rendered":"http:\/\/sokadohi.cyon.site\/produkt\/it8733\/"},"modified":"2026-07-15T19:10:00","modified_gmt":"2026-07-15T19:10:00","slug":"it8733","status":"publish","type":"product","link":"https:\/\/ccontrols.shop\/de\/product\/it8733\/","title":{"rendered":"IT8733"},"content":{"rendered":"<\/p>\n<div class=\"magezon-builder magezon-builder-preload\">\n<div class=\"sbnqnes mgz-element mgz-element-row full_width_row\">\n<div class=\"mgz-element-inner sbnqnes-s\">\n<div class=\"inner-content mgz-container\">\n<div class=\"ps74v94 mgz-element mgz-element-column mgz-col-md-6\">\n<div class=\"mgz-element-inner ps74v94-s\">\n<div class=\"f6kky5v mgz-element mgz-child mgz-element-text\">\n<div class=\"mgz-element-inner f6kky5v-s\">\n<h1>ITECH IT8733&nbsp;<\/h1>\n<p>- IT8733 DC-E-Load, 1 Kanal: 80 V \/ 120 A \/ 600 W<br \/>Dieses E-Load-Modul passt in einen Steckplatz eines modularen E-Load-Hauptrahmens vom Typ IT8701 oder IT8702. <br \/>Es kann nicht ohne einen Hauptrahmen verwendet werden.<\/p>\n<p>Die programmierbare elektronische Gleichstromlast der IT8700-Serie verf\u00fcgt \u00fcber ein Design mit austauschbaren Modulen, wobei ein einzelner Rahmen 8 Kan\u00e4le steuert und im Transientenmodus mit erweiterter Hauptrahmenerweiterung bis zu 25 kHz 16 Kan\u00e4le unterst\u00fctzt, was Ihre Test-Effizienz durch hohe Aufl\u00f6sung und Genauigkeit verbessert. Anwender k\u00f6nnen je nach Anzahl der Kan\u00e4le und Leistungsanforderungen frei zwischen den 8 Lastmodulen w\u00e4hlen; die Steuerung erfolgt entweder \u00fcber das Bedienfeld des Hauptger\u00e4ts oder \u00fcber die Software IT9000-PV8700 via integrierter LAN-\/RS232-\/USB-Schnittstelle. Das IT8700 verf\u00fcgt \u00fcber eine einstellbare Steigung, eine Listenfunktion, eine automatische Testfunktion und weitere Funktionen; die automatische Testfunktion kann so eingestellt werden, dass sie unter CC\/CV\/CR\/CP arbeitet, und ist f\u00fcr den Einsatz in der Forschung und Entwicklung sowie in der Fertigungslinie geeignet. Das IT8700 verf\u00fcgt \u00fcber eine Selbstdiagnose sowie umfassende Schutzfunktionen wie OVP, OCP, OPP, OTP usw., die die Sicherheit des Bedieners gew\u00e4hrleisten. <\/p>\n<p>Wichtigste Merkmale:<br \/>- Herausnehmbare Module f\u00fcr eine einfache Systemkonfiguration<br \/>- Das Zweikanalmodul kann die Informationen beider Kan\u00e4le gleichzeitig anzeigen<br \/>- Einzelrahmen mit bis zu 8 Kan\u00e4len, erweiterter Rahmen mit bis zu 16 Kan\u00e4len<br \/>- Funktion zur dynamischen Stromverteilung f\u00fcr zwei Kan\u00e4le<br \/>- Messaufl\u00f6sung: 0,1 mV\/0,01 mA<br \/>- Messung des Kurzschluss-Spitzenstroms und der Kurzschluss-Spitzenspannung<br \/>- Messgeschwindigkeit f\u00fcr Spannung und Strom bis zu 50 kHz<br \/>- Einstellbare Anstiegs- und Abfallflanke des Stroms<br \/>- Automatische Testfunktion mit automatischer Beurteilung, ob das Testergebnis die festgelegten Spezifikationen \u00fcberschreitet<br \/>- Simulieren Sie im Listenmodus verschiedene Wellenformen unter Last<br \/>- Dynamikmodus bis zu 25 kHz<br \/>- Die automatische Testfunktion kann automatisch feststellen, ob die Testergebnisse die festgelegten Spezifikationen \u00fcberschreiten<br \/>- Gleichzeitiger Betrieb mehrerer S\u00e4tze elektronischer Lastmodule<br \/>- OVP \/ OCP \/ OPP \/ OTP \/ Verpolungsschutzfunktion<br \/>- Integrierte Kommunikationsschnittstelle f\u00fcr Ethernet, USB und RS232<br \/>- Unterst\u00fctzung der R\u00fcckfahrwarnfunktion<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"qr8ht0l mgz-element mgz-element-column mgz-col-md-6 mgz-element-column-empty\">\n<div class=\"mgz-element-inner qr8ht0l-s\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<hr>\n<h3>Warum sollten Sie sich f\u00fcr den IT8733 entscheiden?<\/h3>\n<p>Das Modell IT8733 wurde entwickelt, um selbst unter anspruchsvollsten Bedingungen un\u00fcbertroffene Zuverl\u00e4ssigkeit und Genauigkeit zu gew\u00e4hrleisten. Dieses Ger\u00e4t wurde speziell f\u00fcr Ingenieure konzipiert, denen Leistung besonders wichtig ist, und liefert zuverl\u00e4ssige Ergebnisse in den Bereichen Forschung und Entwicklung, Qualit\u00e4tssicherung sowie industrielle Instandhaltung. Kontaktieren Sie uns noch heute, um individuellen technischen Support zu erhalten oder Anfragen zu Gro\u00dfbestellungen zu stellen. <\/p>\n<p><a href=\"https:\/\/ccontrols.shop\/wp-content\/uploads\/2026\/05\/ITech_IT8700_Series_Datasheet.pdf\">ITech_IT8700_Serie_Datenblatt<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"custom-attribute-values-only\" style=\"font-size: 15px; font-weight: 500; line-height: 1.4; color: #333;\">DC Load, 1 CH, 80 V, 120 A, 500 W, IT8700, CC, 0.4 A\/us<\/div>\n","protected":false},"featured_media":38020,"comment_status":"closed","ping_status":"open","template":"","meta":{"content-type":""},"product_brand":[2898],"product_cat":[256],"product_tag":[],"class_list":["post-2894","product","type-product","status-publish","has-post-thumbnail","product_brand-itech","product_cat-stromversorgungen","pa_compatibility-it8700","pa_current-120-a","pa_load-type-dc-load","pa_modes-cc-cp-cv","pa_power-6765","pa_power-unit-w","pa_slew-rate-0-4-a-us","pa_voltage-80-v","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author","","first","instock","taxable","shipping-taxable","product-type-simple"],"builder_content":"","_links":{"self":[{"href":"https:\/\/ccontrols.shop\/de\/wp-json\/wp\/v2\/product\/2894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccontrols.shop\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ccontrols.shop\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ccontrols.shop\/de\/wp-json\/wp\/v2\/comments?post=2894"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccontrols.shop\/de\/wp-json\/wp\/v2\/media\/38020"}],"wp:attachment":[{"href":"https:\/\/ccontrols.shop\/de\/wp-json\/wp\/v2\/media?parent=2894"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ccontrols.shop\/de\/wp-json\/wp\/v2\/product_brand?post=2894"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ccontrols.shop\/de\/wp-json\/wp\/v2\/product_cat?post=2894"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ccontrols.shop\/de\/wp-json\/wp\/v2\/product_tag?post=2894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}