{"id":3030,"date":"2026-05-08T14:14:27","date_gmt":"2026-05-08T14:14:27","guid":{"rendered":"http:\/\/sokadohi.cyon.site\/produkt\/it6152\/"},"modified":"2026-07-13T16:42:05","modified_gmt":"2026-07-13T16:42:05","slug":"it6152","status":"publish","type":"product","link":"https:\/\/ccontrols.shop\/de\/product\/it6152\/","title":{"rendered":"IT6152"},"content":{"rendered":"<\/p>\n<div class=\"magezon-builder magezon-builder-preload\">\n<div class=\"yxgrpmo mgz-element mgz-element-row full_width_row\">\n<div class=\"mgz-element-inner yxgrpmo-s\">\n<div class=\"inner-content mgz-container\">\n<div class=\"vnx5qo0 mgz-element mgz-element-column mgz-col-md-6\">\n<div class=\"mgz-element-inner vnx5qo0-s\">\n<div class=\"i761wax mgz-element mgz-child mgz-element-text\">\n<div class=\"mgz-element-inner i761wax-s\">\n<h1>ITECH - <span>IT6152 <\/span><\/h1>\n<p><span><\/span><\/p>\n<p>- IT6153 Programmierbares lineares DC-Netzteil 30V \/ 18A \/ 540W<\/p><\/div>\n<div class=\"mgz-element-inner i761wax-s\">Die IT6100 Serie garantiert pr\u00e4zise Messungen mit 0,1 mV \/ 0,1 mA hoher Aufl\u00f6sung und hoher Genauigkeit. Mit dem High-Speed-List-Modus erzeugt es Spannungswellenformen, um den Anforderungen von Hochgeschwindigkeitstests gerecht zu werden. Die IT6100 Serie hat ein eingebautes 5\u00c2\u00bd digitales Voltmeter und Milliohm-Meter, mit denen zus\u00e4tzliche Signale gemessen werden k\u00f6nnen. Die IT6100 Serie unterst\u00fctzt das SCPI-Kommunikationsprotokoll, GPIB \/ USB \/ RS232 Schnittstellen sind optional und k\u00f6nnen mit externen Adaptern hinzugef\u00fcgt werden. <\/div>\n<div class=\"mgz-element-inner i761wax-s\">Hauptmerkmale:<br \/>- Lineares programmierbares Netzteil<br \/>- Helles VFD-Display<br \/>- Geringe Restwelligkeit und geringes Rauschen<br \/>- Eingebautes 5\u00c2\u00bd digitales Voltmeter<br \/>- Unterst\u00fctzt SCPI-Kommunikationsprotokoll<br \/>- Optionale GPIB \/ USB \/ RS232-Schnittstellen<br \/>- Hohe Genauigkeit und hohe Aufl\u00f6sung<br \/>- PC-\u00dcberwachungssoftware<br \/>- Betrieb im Listenmodus, schnelle Einstellung der Ausgangsspannung und des Stroms<br \/>- Geeignet f\u00fcr 19&#8243;-Standard-Rackeinbau<\/div>\n<div class=\"mgz-element-inner i761wax-s\"><i>Im Datenblatt finden Sie eine vollst\u00e4ndige Liste der Funktionen und Merkmale.<\/i><\/p>\n<p><span style=\"font-size:12px;\"><em><\/em><\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"rga74or mgz-element mgz-element-column mgz-col-md-6 mgz-element-column-empty\">\n<div class=\"mgz-element-inner rga74or-s\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<hr>\n<h3>Warum sollten Sie sich f\u00fcr den IT6152 entscheiden?<\/h3>\n<p>Dieses Ger\u00e4t wurde entwickelt, um die h\u00f6chsten Anforderungen an Genauigkeit und Zuverl\u00e4ssigkeit in anspruchsvollen Umgebungen zu erf\u00fcllen. Ob in der Forschung und Entwicklung, bei der Qualit\u00e4tskontrolle oder bei Produktionstests, es bietet die konsistente Leistung, auf die sich Profis verlassen. F\u00fcr eine technische Beratung und weitere Details wenden Sie sich bitte noch heute an unser Expertenteam. <\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"custom-attribute-values-only\" style=\"font-size: 15px; font-weight: 500; line-height: 1.4; color: #333;\">DC Versorgung, 30 V, 0.125 A, 150 W, 1mV \/ 1mA, 0.0001 Acc, &lt;1mVrms, USB<\/div>\n","protected":false},"featured_media":38029,"comment_status":"closed","ping_status":"open","template":"","meta":{"content-type":""},"product_brand":[2898],"product_cat":[256],"product_tag":[],"class_list":["post-3030","product","type-product","status-publish","has-post-thumbnail","product_brand-itech","product_cat-stromversorgungen","pa_current-0-125","pa_interface-rs232","pa_interface-usb","pa_power-6708","pa_power-type-dc-versorgung","pa_power-unit-w","pa_res-1mv-1ma","pa_ripple-1mvrms","pa_voltage-30-v","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author","","first","instock","taxable","shipping-taxable","product-type-simple"],"jetpack_sharing_enabled":true,"builder_content":"","_links":{"self":[{"href":"https:\/\/ccontrols.shop\/de\/wp-json\/wp\/v2\/product\/3030","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccontrols.shop\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ccontrols.shop\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ccontrols.shop\/de\/wp-json\/wp\/v2\/comments?post=3030"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccontrols.shop\/de\/wp-json\/wp\/v2\/media\/38029"}],"wp:attachment":[{"href":"https:\/\/ccontrols.shop\/de\/wp-json\/wp\/v2\/media?parent=3030"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ccontrols.shop\/de\/wp-json\/wp\/v2\/product_brand?post=3030"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ccontrols.shop\/de\/wp-json\/wp\/v2\/product_cat?post=3030"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ccontrols.shop\/de\/wp-json\/wp\/v2\/product_tag?post=3030"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}