{"id":3179,"date":"2026-05-08T14:27:51","date_gmt":"2026-05-08T14:27:51","guid":{"rendered":"http:\/\/sokadohi.cyon.site\/produkt\/e36234a\/"},"modified":"2026-07-15T19:10:54","modified_gmt":"2026-07-15T19:10:54","slug":"e36234a","status":"publish","type":"product","link":"https:\/\/ccontrols.shop\/de\/product\/e36234a\/","title":{"rendered":"E36234A"},"content":{"rendered":"<div class=\"magezon-builder magezon-builder-preload\">\n<div class=\"kush2ns mgz-element mgz-element-row full_width_row\">\n<div class=\"mgz-element-inner kush2ns-s\">\n<div class=\"inner-content mgz-container\">\n<div class=\"sah1po4 mgz-element mgz-element-column mgz-col-md-6\">\n<div class=\"mgz-element-inner sah1po4-s\">\n<div class=\"u5e5jgv mgz-element mgz-child mgz-element-text\">\n<div class=\"mgz-element-inner u5e5jgv-s\">\n<h3>KEYSIGHT E36234A<\/h3>\n<p>Das Netzteil E36233A von Keysight mit automatischer Bereichswahl ist die ideale Wahl f\u00fcr Anwendungen, bei denen eine h\u00f6here Leistung erforderlich ist. Die beiden unabh\u00e4ngigen 200-W-Ausg\u00e4nge eines Zweikanalger\u00e4ts k\u00f6nnen bis zu 400 W liefern. Dank der automatischen Bereichswahl liefert das Netzteil bei allen verschiedenen Spannungen den maximalen Strom. Die automatische Serien- und Parallelschaltung bei den Zweikanalmodellen bietet maximale Spannung oder maximalen Strom bis zu einer Leistung von 400 W. <\/p>\n<p><strong>Wichtigste Merkmale<\/strong><br \/>&gt; Doppelausgang: 60 V, 10 A, 400 W<br \/>&gt; Kombinierte Ausg\u00e4nge der Auto-Serie f\u00fcr h\u00f6here Spannungen bis zu 120 V.<br \/>&gt; Stromversorgung mit automatischer Bereichswahl, die bei allen Spannungsstufen einen h\u00f6heren Strom liefert<br \/>&gt; Regelung des Einschaltstroms mittels variabler Anstiegsgeschwindigkeit<br \/>&gt; Sorgen Sie f\u00fcr den Schutz Ihrer Ger\u00e4te durch den Einsatz von \u00dcberspannungs-, \u00dcberstrom- und \u00dcbertemperaturschutzma\u00dfnahmen.<br \/>&gt; Profitieren Sie von einem Wert von &lt;350 \u00b5Vrms f\u00fcr eine Ausgangsspannung mit geringer Welligkeit und geringem Rauschen<br \/>&gt; Verbessern Sie die Lastregelung mit einer Vierdraht-Messung<br \/>&gt; Messen Sie die Leistung \u00fcber einen bestimmten Zeitraum hinweg mit einem integrierten Datenlogger<br \/>&gt; Vereinfachung der USB-, LAN- (LXI Core) und optionalen GPIB-Anbindung<\/p>\n<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"hmuaua0 mgz-element mgz-element-column mgz-col-md-6 mgz-element-column-empty\">\n<div class=\"mgz-element-inner hmuaua0-s\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<hr>\n<h3>Warum sollten Sie sich f\u00fcr das Modell E36234A entscheiden?<\/h3>\n<p>Das Modell E36234A wurde entwickelt, um selbst unter anspruchsvollsten Bedingungen un\u00fcbertroffene Zuverl\u00e4ssigkeit und Genauigkeit zu gew\u00e4hrleisten. Dieses Ger\u00e4t wurde f\u00fcr Ingenieure konzipiert, die besonderen Wert auf Leistung legen, und gew\u00e4hrleistet stabile Ergebnisse in den Bereichen Forschung und Entwicklung, Qualit\u00e4tssicherung sowie industrielle Instandhaltung. Kontaktieren Sie uns noch heute, um individuellen technischen Support zu erhalten oder Anfragen zu Gro\u00dfbestellungen zu stellen. <\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"custom-attribute-values-only\" style=\"font-size: 15px; font-weight: 500; line-height: 1.4; color: #333;\">10 A, DC Versorgung, 2-CH, 400 W, 60 V, 1mV \/ 1mA, LAN<\/div>\n","protected":false},"featured_media":41819,"comment_status":"closed","ping_status":"open","template":"","meta":{"content-type":""},"product_brand":[1743],"product_cat":[256],"product_tag":[],"class_list":["post-3179","product","type-product","status-publish","has-post-thumbnail","product_brand-keysight","product_cat-stromversorgungen","pa_current-10-a","pa_interface-lan-usb","pa_power-6707","pa_power-type-dc-versorgung","pa_power-unit-w","pa_res-1mv-1ma","pa_voltage-60-v","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author","","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"builder_content":"","_links":{"self":[{"href":"https:\/\/ccontrols.shop\/de\/wp-json\/wp\/v2\/product\/3179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccontrols.shop\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ccontrols.shop\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ccontrols.shop\/de\/wp-json\/wp\/v2\/comments?post=3179"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccontrols.shop\/de\/wp-json\/wp\/v2\/media\/41819"}],"wp:attachment":[{"href":"https:\/\/ccontrols.shop\/de\/wp-json\/wp\/v2\/media?parent=3179"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ccontrols.shop\/de\/wp-json\/wp\/v2\/product_brand?post=3179"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ccontrols.shop\/de\/wp-json\/wp\/v2\/product_cat?post=3179"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ccontrols.shop\/de\/wp-json\/wp\/v2\/product_tag?post=3179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}