{"id":1510,"date":"2026-05-08T13:50:31","date_gmt":"2026-05-08T13:50:31","guid":{"rendered":"http:\/\/sokadohi.cyon.site\/produkt\/tgp3152\/"},"modified":"2026-07-15T18:20:23","modified_gmt":"2026-07-15T18:20:23","slug":"tgp3152","status":"publish","type":"product","link":"https:\/\/ccontrols.shop\/fr\/product\/tgp3152\/","title":{"rendered":"TGP3152"},"content":{"rendered":"<p><strong>Aim-TTi TGP3152 \u00ab G\u00e9n\u00e9rateur de signaux \u00e0 deux canaux (impulsions et formes d&rsquo;onde universelles) \u00bb<\/strong><\/p>\n<p><strong>L&rsquo;Aim-TTi TGP3152<\/strong> est un <strong>g\u00e9n\u00e9rateur de signaux \u00e0 deux canaux<\/strong> haute performance, capable de produire <strong>des impulsions et des formes d&rsquo;onde universelles<\/strong>, con\u00e7u pour les environnements exigeants de laboratoire, de recherche et de d\u00e9veloppement \u00e9lectronique. Faisant partie de la s\u00e9rie TGP3100, il combine les fonctionnalit\u00e9s d&rsquo;un <strong>g\u00e9n\u00e9rateur d&rsquo;impulsions, d&rsquo;un g\u00e9n\u00e9rateur de formes d&rsquo;onde arbitraires, d&rsquo;un g\u00e9n\u00e9rateur de fonctions et d&rsquo;un g\u00e9n\u00e9rateur de bruit<\/strong> en un seul instrument polyvalent. <\/p>\n<p>Le g\u00e9n\u00e9rateur prend en charge des formes d&rsquo;onde impulsionnelles dont les fr\u00e9quences <strong>vont de 1 mHz \u00e0 50 MHz<\/strong>, offrant ainsi un contr\u00f4le temporel extr\u00eamement pr\u00e9cis avec des r\u00e9solutions de largeur d&rsquo;impulsion, de retard et de p\u00e9riode pouvant descendre jusqu&rsquo;\u00e0 <strong>100 ps<\/strong>. Il est donc id\u00e9al pour les tests de circuits num\u00e9riques, l&rsquo;analyse temporelle et les applications de conditionnement de signaux. <span><\/span><\/p>\n<p>Outre la g\u00e9n\u00e9ration d&rsquo;impulsions, le TGP3152 propose <strong>16 types de formes d&rsquo;onde<\/strong>, notamment des signaux sinuso\u00efdaux, carr\u00e9s, triangulaires et en rampe, ainsi que la g\u00e9n\u00e9ration de formes d&rsquo;onde arbitraires avec <strong>une r\u00e9solution verticale de 16 bits et un taux d&rsquo;\u00e9chantillonnage pouvant atteindre 800 MS\/s<\/strong>, pour une reproduction pr\u00e9cise des signaux. <span><\/span><\/p>\n<p>Des capacit\u00e9s de modulation avanc\u00e9es telles que <strong>l&rsquo;AM, la FM, la PM, la FSK, la BPSK, la PWM et la PDM<\/strong> permettent aux ing\u00e9nieurs de simuler des conditions de signal complexes et d&rsquo;effectuer une analyse d\u00e9taill\u00e9e des signaux. L&rsquo;appareil prend \u00e9galement en charge le fonctionnement d\u00e9clench\u00e9 ou synchronis\u00e9 \u00e0 l&rsquo;aide de sources de d\u00e9clenchement internes ou externes. <span><\/span><\/p>\n<p>Gr\u00e2ce \u00e0 <strong>ses interfaces USB et LAN (LXI), ainsi qu&rsquo;\u00e0 l&rsquo;interface GPIB en option<\/strong>, le TGP3152 s&rsquo;int\u00e8gre facilement dans des syst\u00e8mes de test automatis\u00e9s et des environnements de mesure pilot\u00e9s par ordinateur. <span><\/span><\/p>\n<p>Gr\u00e2ce \u00e0 son architecture \u00e0 deux canaux, \u00e0 sa grande pr\u00e9cision de synchronisation et \u00e0 ses capacit\u00e9s \u00e9tendues en mati\u00e8re de formes d&rsquo;onde, le TGP3152 est id\u00e9al pour les laboratoires de d\u00e9veloppement, les environnements de recherche et les applications de test en production.<\/p>\n<hr>\n<h1>Principales caract\u00e9ristiques<\/h1>\n<ul>\n<li>\n<p><strong>G\u00e9n\u00e9rateur d&rsquo;impulsions \u00e0 deux canaux et de formes d&rsquo;onde universelles<\/strong><\/p>\n<\/li>\n<li>\n<p>Plage de fr\u00e9quences : <strong>1 mHz \u00e0 50 MHz<\/strong> <span><\/span><\/p>\n<\/li>\n<li>\n<p>G\u00e9n\u00e9ration d&rsquo;impulsions, de doubles impulsions, de s\u00e9quences d&rsquo;impulsions et de formes d&rsquo;onde PRBS <span><\/span><\/p>\n<\/li>\n<li>\n<p><strong>R\u00e9solution de la largeur d&rsquo;impulsion, du retard et de la p\u00e9riode allant jusqu&rsquo;\u00e0 100 ps<\/strong> <span><\/span><\/p>\n<\/li>\n<li>\n<p>Temps de mont\u00e9e et de descente r\u00e9glables ind\u00e9pendamment (\u00e0 partir d&rsquo;environ <strong>5 ns<\/strong>) <span><\/span><\/p>\n<\/li>\n<li>\n<p><strong>G\u00e9n\u00e9ration de formes d&rsquo;onde arbitraires avec une r\u00e9solution de 16 bits et un taux d&rsquo;\u00e9chantillonnage de 800 MS\/s<\/strong> <span><\/span><\/p>\n<\/li>\n<li>\n<p><strong>G\u00e9n\u00e9rateur de bruit<\/strong> int\u00e9gr\u00e9 <strong>pouvant atteindre 25 MHz<\/strong> <span><\/span><\/p>\n<\/li>\n<li>\n<p>Nombreuses options de modulation : <strong>AM, FM, PM, FSK, BPSK, PWM, PDM<\/strong> <span><\/span><\/p>\n<\/li>\n<li>\n<p><strong>Interfaces USB et LAN (LXI)<\/strong>, GPIB en option <span><\/span><\/p>\n<\/li>\n<li>\n<p>Capacit\u00e9 de commande en sortie pouvant atteindre <strong>20 V cr\u00eate \u00e0 cr\u00eate sur une charge de 50 \u00ce\u00a9<\/strong> <span><\/span><\/p>\n<\/li>\n<\/ul>\n<hr>\n<h1>Applications typiques<\/h1>\n<ul>\n<li>\n<p>Test des circuits num\u00e9riques et analyse des temps de propagation<\/p>\n<\/li>\n<li>\n<p>Simulation de signaux et g\u00e9n\u00e9ration de formes d&rsquo;onde<\/p>\n<\/li>\n<li>\n<p>D\u00e9veloppement de syst\u00e8mes de radiofr\u00e9quence et de communication<\/p>\n<\/li>\n<li>\n<p>D\u00e9veloppement et prototypage de composants \u00e9lectroniques<\/p>\n<\/li>\n<li>\n<p>Essais de production et contr\u00f4le qualit\u00e9<\/p>\n<\/li>\n<\/ul>\n<hr>\n<h3>Pourquoi choisir le TGP3152 ?<\/h3>\n<p>Cet appareil a \u00e9t\u00e9 con\u00e7u pour r\u00e9pondre aux normes les plus strictes en mati\u00e8re de pr\u00e9cision et de fiabilit\u00e9 dans des environnements exigeants. Que ce soit pour la recherche et le d\u00e9veloppement, le contr\u00f4le qualit\u00e9 ou les essais de production, il offre les performances constantes sur lesquelles comptent les professionnels. Pour toute consultation technique ou pour plus d&rsquo;informations, veuillez contacter d\u00e8s aujourd&rsquo;hui notre \u00e9quipe d&rsquo;experts. <\/p>\n<p><a href=\"https:\/\/ccontrols.shop\/wp-content\/uploads\/2026\/05\/AIM-TGP3100_series_pulse_generator_data_sheet-Iss3.pdf\">Fiche technique du g\u00e9n\u00e9rateur d&rsquo;impulsions de la s\u00e9rie AIM-TGP3100 - \u00c9dition n\u00b0 3<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"custom-attribute-values-only\" style=\"font-size: 15px; font-weight: 500; line-height: 1.4; color: #333;\">50 MHz, 50, G\u00e9n\u00e9ration d&rsquo;impulsions, 0.1 Hz &#8211; 50 MHz, 2-CH, 800 MSa\/s, &lt;30 ps, 8 ns, Couleur TFT, LAN<\/div>\n","protected":false},"featured_media":59421,"comment_status":"closed","ping_status":"open","template":"","meta":{"content-type":""},"product_brand":[3937],"product_cat":[298],"product_tag":[],"class_list":["post-1510","product","type-product","status-publish","has-post-thumbnail","product_brand-aim-tti","product_cat-generateurs","pa_display-couleur-tft-2","pa_freq-range-0-1-hz-50-mhz","pa_frequency-range-for-filter-6950","pa_interface-lan-usb","pa_jitter-30-ps","pa_pulse-width-8-ns","pa_sample-rate-800-msa-s","pa_waveform-generation-dimpulsions","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author","","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"builder_content":"","_links":{"self":[{"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/product\/1510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/comments?post=1510"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/media\/59421"}],"wp:attachment":[{"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/media?parent=1510"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/product_brand?post=1510"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/product_cat?post=1510"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/product_tag?post=1510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}