{"id":1570,"date":"2026-05-08T13:51:26","date_gmt":"2026-05-08T13:51:26","guid":{"rendered":"http:\/\/sokadohi.cyon.site\/produkt\/tsx3510\/"},"modified":"2026-07-15T18:52:02","modified_gmt":"2026-07-15T18:52:02","slug":"tsx3510","status":"publish","type":"product","link":"https:\/\/ccontrols.shop\/fr\/product\/tsx3510\/","title":{"rendered":"TSX3510"},"content":{"rendered":"<p><strong>Aim-TTi TSX3510 \u00ab Alimentation CC lin\u00e9aire haute performance \u00bb<\/strong><\/p>\n<p><strong>L&rsquo;Aim-TTi TSX3510<\/strong> est une alimentation lin\u00e9aire \u00e0 courant continu de pr\u00e9cision, con\u00e7ue pour fournir une alimentation stable et fiable destin\u00e9e aux applications de laboratoire, de d\u00e9veloppement et industrielles. Avec une plage de sortie r\u00e9glable de <strong>0 \u00e0 35 V et jusqu&rsquo;\u00e0 10 A<\/strong>, elle offre la flexibilit\u00e9 n\u00e9cessaire pour un large \u00e9ventail de t\u00e2ches de test et de d\u00e9veloppement \u00e9lectroniques. <\/p>\n<p>Con\u00e7u \u00e0 partir d&rsquo;une technologie de r\u00e9gulation lin\u00e9aire de haute qualit\u00e9, le TSX3510 offre <strong>une sortie \u00e0 faible bruit ainsi qu&rsquo;une excellente r\u00e9gulation de charge et de tension d&rsquo;alimentation<\/strong>, ce qui le rend particuli\u00e8rement adapt\u00e9 \u00e0 l&rsquo;alimentation de circuits et de composants \u00e9lectroniques sensibles.<\/p>\n<p>Le panneau avant intuitif permet un r\u00e9glage pr\u00e9cis de la tension et du courant, tandis que l&rsquo;\u00e9cran num\u00e9rique clair permet un suivi pr\u00e9cis des param\u00e8tres de sortie. La conception robuste de ce mod\u00e8le de table garantit un fonctionnement fiable dans les environnements exigeants de laboratoire et de production. <\/p>\n<hr>\n<h1>Principales caract\u00e9ristiques<\/h1>\n<ul>\n<li>\n<p><strong>Alimentation lin\u00e9aire \u00e0 courant continu \u00e0 sortie unique<\/strong><\/p>\n<\/li>\n<li>\n<p>Tension de sortie : <strong>0 \u00e0 35 V<\/strong><\/p>\n<\/li>\n<li>\n<p>Courant de sortie : <strong>0 \u00e0 10 A<\/strong><\/p>\n<\/li>\n<li>\n<p>Faible niveau sonore et excellente stabilit\u00e9<\/p>\n<\/li>\n<li>\n<p>Contr\u00f4le de haute pr\u00e9cision de la tension et du courant<\/p>\n<\/li>\n<li>\n<p>Excellente r\u00e9gulation de charge et de tension<\/p>\n<\/li>\n<li>\n<p>Affichage num\u00e9rique clair de la tension et du courant<\/p>\n<\/li>\n<li>\n<p>Conception robuste de qualit\u00e9 laboratoire<\/p>\n<\/li>\n<\/ul>\n<hr>\n<h1>Applications typiques<\/h1>\n<ul>\n<li>\n<p>D\u00e9veloppement et prototypage de composants \u00e9lectroniques<\/p>\n<\/li>\n<li>\n<p>Essais et mesures en laboratoire<\/p>\n<\/li>\n<li>\n<p>Production et contr\u00f4le qualit\u00e9<\/p>\n<\/li>\n<li>\n<p>Environnements d&rsquo;entretien et de r\u00e9paration<\/p>\n<\/li>\n<li>\n<p>Laboratoires p\u00e9dagogiques<\/p>\n<\/li>\n<\/ul>\n<hr>\n<h3>Pourquoi choisir le TSX3510 ?<\/h3>\n<p>Cet appareil a \u00e9t\u00e9 con\u00e7u pour r\u00e9pondre aux normes les plus strictes en mati\u00e8re de pr\u00e9cision et de fiabilit\u00e9 dans des environnements exigeants. Que ce soit pour la recherche et le d\u00e9veloppement, le contr\u00f4le qualit\u00e9 ou les essais de production, il offre les performances constantes sur lesquelles comptent les professionnels. Pour toute consultation technique ou pour plus d&rsquo;informations, veuillez contacter d\u00e8s aujourd&rsquo;hui notre \u00e9quipe d&rsquo;experts. <\/p>\n<p><a href=\"https:\/\/ccontrols.shop\/wp-content\/uploads\/2026\/05\/AIM\">OBJECTIF<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"custom-attribute-values-only\" style=\"font-size: 15px; font-weight: 500; line-height: 1.4; color: #333;\">10 A, Alimentation en courant continu, 35 V, 350 W, 0.0001 Acc, Aucun, Num\u00e9rique, 0.0001, Control<\/div>\n","protected":false},"featured_media":59439,"comment_status":"closed","ping_status":"open","template":"","meta":{"content-type":""},"product_brand":[3937],"product_cat":[338],"product_tag":[],"class_list":["post-1570","product","type-product","status-publish","has-post-thumbnail","product_brand-aim-tti","product_cat-alimentations","pa_current-10-a","pa_display-numerique","pa_interface-aucun","pa_manual-control","pa_power-6724","pa_power-type-alimentation-en-courant-continu","pa_power-unit-w","pa_regulation-0-0001","pa_voltage-35-v","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author","","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"builder_content":"","_links":{"self":[{"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/product\/1570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/comments?post=1570"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/media\/59439"}],"wp:attachment":[{"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/media?parent=1570"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/product_brand?post=1570"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/product_cat?post=1570"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/product_tag?post=1570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}