{"id":2748,"date":"2026-05-08T14:20:04","date_gmt":"2026-05-08T14:20:04","guid":{"rendered":"http:\/\/sokadohi.cyon.site\/produkt\/34922a\/"},"modified":"2026-07-15T15:36:30","modified_gmt":"2026-07-15T15:36:30","slug":"34922a","status":"publish","type":"product","link":"https:\/\/ccontrols.shop\/fr\/product\/34922a\/","title":{"rendered":"34922A"},"content":{"rendered":"<h1>KEYSIGHT - 34922A&nbsp; &nbsp;&nbsp;<\/h1>\n<p>- Module multiplexeur d&rsquo;armature \u00e0 70 canaux pour le 34980A&nbsp; &nbsp;&nbsp;<\/p>\n<p>Le module Keysight 34922A destin\u00e9 \u00e0 l&rsquo;unit\u00e9 multifonction de commutation et de mesure 34980A offre une commutation par multiplexeur \u00e0 haute densit\u00e9 dans un format compact. Il combine une commutation multifonction \u00e0 haute densit\u00e9 avec des vitesses de balayage de 100 canaux par seconde, ce qui lui permet de r\u00e9pondre \u00e0 un large \u00e9ventail d&rsquo;applications d&rsquo;acquisition de donn\u00e9es. Les mesures de courant peuvent \u00eatre effectu\u00e9es \u00e0 l&rsquo;aide de r\u00e9sistances shunt fournies par l&rsquo;utilisateur. Les connecteurs D-Sub standard \u00e0 78 broches permettent une utilisation avec des c\u00e2bles standard, des borniers ou des solutions d&rsquo;interconnexion en s\u00e9rie. &nbsp;<\/p>\n<p>Caract\u00e9ristiques principales et sp\u00e9cifications :<br \/>- 70 canaux \u00e0 2 fils<br \/>- Possibilit\u00e9 de combiner des configurations \u00e0 2 ou 4 fils<br \/>- Balayage \u00e0 100 canaux\/s<br \/>- Commutateur 300 V, 1 A ; courant de transport 2 A<br \/>- Relais \u00e0 armature \u00e0 verrouillage, avec compteur de relais<\/p>\n<hr>\n<h3>Pourquoi choisir le mod\u00e8le 34922A ?<\/h3>\n<p>Le mod\u00e8le 34922A est con\u00e7u pour offrir une fiabilit\u00e9 et une pr\u00e9cision in\u00e9gal\u00e9es dans les environnements les plus exigeants. Destin\u00e9 aux ing\u00e9nieurs qui accordent la priorit\u00e9 \u00e0 la performance, cet appareil garantit des r\u00e9sultats stables pour la R&#038;D, l&rsquo;assurance qualit\u00e9 et la maintenance industrielle. Contactez-nous d\u00e8s aujourd&rsquo;hui pour b\u00e9n\u00e9ficier d&rsquo;une assistance technique personnalis\u00e9e et pour toute demande de renseignements concernant les achats en gros. <\/p>\n<p><a href=\"https:\/\/ccontrols.shop\/wp-content\/uploads\/2026\/05\/34980A20Data20Acquisition20System.pdf\">34980A20 Syst\u00e8me d&rsquo;acquisition de donn\u00e9es<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"custom-attribute-values-only\" style=\"font-size: 15px; font-weight: 500; line-height: 1.4; color: #333;\">6.5 Digit, Multiplexer, 70-CH, Armature, D-Sub, 300 V, 25 MHz, 34980A, 6.5<\/div>\n","protected":false},"featured_media":58531,"comment_status":"closed","ping_status":"open","template":"","meta":{"content-type":""},"product_brand":[1738],"product_cat":[6468],"product_tag":[],"class_list":["post-2748","product","type-product","status-publish","has-post-thumbnail","product_brand-keysight","product_cat-compteurs-ameliorations-cachees","pa_bw-25-mhz","pa_compatibility-34980a","pa_connection-d-sub","pa_isolation-yes","pa_max-volt-300-v","pa_module-type-multiplexer","pa_resolution-digits-6-5-digit","pa_resolution-meter-6-5","pa_type-2-armature","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author","","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"builder_content":"","_links":{"self":[{"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/product\/2748","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/comments?post=2748"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/media\/58531"}],"wp:attachment":[{"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/media?parent=2748"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/product_brand?post=2748"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/product_cat?post=2748"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/product_tag?post=2748"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}