{"id":4247,"date":"2026-05-08T15:01:26","date_gmt":"2026-05-08T15:01:26","guid":{"rendered":"http:\/\/sokadohi.cyon.site\/produkt\/dg1022z\/"},"modified":"2026-07-15T18:26:28","modified_gmt":"2026-07-15T18:26:28","slug":"dg1022z","status":"publish","type":"product","link":"https:\/\/ccontrols.shop\/fr\/product\/dg1022z\/","title":{"rendered":"DG1022Z"},"content":{"rendered":"<h1>RIGOL - DG1022Z&nbsp;<\/h1>\n<p>- G\u00e9n\u00e9rateur de fonctions 25 MHz, 2 canaux, 200 MSa\/s, 14 bits, m\u00e9moire d&rsquo;arbitrage de 2 Mpts, compteur de fr\u00e9quence de 7 chiffres\/s &nbsp;<\/p>\n<p>G\u00e9n\u00e9rateur de fonctions 25 MHz, 2 canaux, 200 MSa\/s, 14 bits, profondeur de m\u00e9moire arbitraire de 2 Mpts, compteur de fr\u00e9quence de 7 chiffres\/s, c\u00e2ble UE&nbsp;<\/p>\n<hr>\n<h3>Pourquoi choisir le DG1022Z ?<\/h3>\n<p>Le DG1022Z est con\u00e7u pour offrir une fiabilit\u00e9 et une pr\u00e9cision in\u00e9gal\u00e9es dans les environnements les plus exigeants. Destin\u00e9 aux ing\u00e9nieurs qui accordent la priorit\u00e9 \u00e0 la performance, cet appareil garantit des r\u00e9sultats stables pour la R&#038;D, l&rsquo;assurance qualit\u00e9 et la maintenance industrielle. Contactez-nous d\u00e8s aujourd&rsquo;hui pour b\u00e9n\u00e9ficier d&rsquo;une assistance technique personnalis\u00e9e et pour toute demande de renseignements concernant les achats en gros. <\/p>\n<p><a href=\"https:\/\/ccontrols.shop\/wp-content\/uploads\/2026\/05\/DG1000Z_DataSheet_EN_tcm30-2815.pdf\">DG1000Z_Fiche technique_FR_tcm30-2815<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"custom-attribute-values-only\" style=\"font-size: 15px; font-weight: 500; line-height: 1.4; color: #333;\">25 MHz, 25, 25, Arb\/Function, 2-CH, 200 MSa\/s, 14-bit, 2 Mpts, Complet, LAN<\/div>\n","protected":false},"featured_media":60078,"comment_status":"closed","ping_status":"open","template":"","meta":{"content-type":""},"product_brand":[1971],"product_cat":[298],"product_tag":[],"class_list":["post-4247","product","type-product","status-publish","has-post-thumbnail","product_brand-rigol","product_cat-generateurs","pa_bandwidth-mhz-11228","pa_frequency-range-for-filter-6946","pa_interface-lan-usb","pa_memory-2-mpts","pa_sample-rate-200-msa-s","pa_vertical-res-14-bit","pa_waveform-arb-function","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author","","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"builder_content":"","_links":{"self":[{"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/product\/4247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/comments?post=4247"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/media\/60078"}],"wp:attachment":[{"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/media?parent=4247"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/product_brand?post=4247"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/product_cat?post=4247"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/product_tag?post=4247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}