{"id":4587,"date":"2026-05-08T15:11:46","date_gmt":"2026-05-08T15:11:46","guid":{"rendered":"http:\/\/sokadohi.cyon.site\/produkt\/dp2031\/"},"modified":"2026-07-15T19:13:43","modified_gmt":"2026-07-15T19:13:43","slug":"dp2031","status":"publish","type":"product","link":"https:\/\/ccontrols.shop\/fr\/product\/dp2031\/","title":{"rendered":"DP2031"},"content":{"rendered":"<h1>RIGOL - DP2031&nbsp;<\/h1>\n<p>- Alimentation CC, 3 canaux, +32 V \/ 3 A, +32 V \/ 3 A, +6 V \/ 5 A, CC, 222 W max.).&nbsp;<\/p>\n<p>Alimentation CC \u00e0 3 canaux de sortie ind\u00e9pendants (+32 V \/ 3 A, +32 V \/ 3 A, +6 V \/ 5 A, CC, 222 W max.). \u00c9cran tactile LCD couleur de 4,3 pouces. Haute r\u00e9solution pour la mesure de courants de faible amplitude \u00e0 partir de 1 \u00b5A. Faible ondulation et faible bruit de sortie &lt;, 350 \u00b5Vrms\/2 mVpp. USB HOST, LAN, E\/S num\u00e9riques et RS232 (de s\u00e9rie) <\/p>\n<hr>\n<h3>Pourquoi choisir le DP2031 ?<\/h3>\n<p>Le DP2031 est con\u00e7u pour offrir une fiabilit\u00e9 et une pr\u00e9cision in\u00e9gal\u00e9es dans les environnements les plus exigeants. Destin\u00e9 aux ing\u00e9nieurs qui accordent la priorit\u00e9 \u00e0 la performance, cet appareil garantit des r\u00e9sultats stables pour la R&#038;D, l&rsquo;assurance qualit\u00e9 et la maintenance industrielle. Contactez-nous d\u00e8s aujourd&rsquo;hui pour b\u00e9n\u00e9ficier d&rsquo;une assistance technique personnalis\u00e9e et pour toute demande de renseignements concernant les achats en gros. <\/p>\n<p><a href=\"https:\/\/ccontrols.shop\/wp-content\/uploads\/2026\/05\/DP2000_DataSheet_EN.pdf\">DP2000_Fiche technique_FR<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"custom-attribute-values-only\" style=\"font-size: 15px; font-weight: 500; line-height: 1.4; color: #333;\">222 W, Alimentation en courant continu, 3-CH, 32V\/32V\/6V, 3A\/3A\/10A, 1mV \/ 1mA, 0.0001 Acc, &lt;350uVrms, LAN<\/div>\n","protected":false},"featured_media":60284,"comment_status":"closed","ping_status":"open","template":"","meta":{"content-type":""},"product_brand":[1971],"product_cat":[338],"product_tag":[],"class_list":["post-4587","product","type-product","status-publish","has-post-thumbnail","product_brand-rigol","product_cat-alimentations","pa_current-3a-3a-10a","pa_interface-lan-usb","pa_power-6837","pa_power-type-alimentation-en-courant-continu","pa_power-unit-w","pa_res-1mv-1ma","pa_ripple-350uvrms","pa_voltage-32v-32v-6v","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author","","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"builder_content":"","_links":{"self":[{"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/product\/4587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/comments?post=4587"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/media\/60284"}],"wp:attachment":[{"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/media?parent=4587"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/product_brand?post=4587"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/product_cat?post=4587"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/product_tag?post=4587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}