{"id":4653,"date":"2026-05-08T15:09:47","date_gmt":"2026-05-08T15:09:47","guid":{"rendered":"http:\/\/sokadohi.cyon.site\/produkt\/dl3021\/"},"modified":"2026-07-13T16:55:10","modified_gmt":"2026-07-13T16:55:10","slug":"dl3021","status":"publish","type":"product","link":"https:\/\/ccontrols.shop\/fr\/product\/dl3021\/","title":{"rendered":"DL3021"},"content":{"rendered":"<h1>RIGOL - DL3021&nbsp;<\/h1>\n<p>- Charge \u00e9lectronique DC pour max. 150V, 40A, 200W. Avec interface USB Host, USB Device et RS232. &nbsp;<\/p>\n<p>Charge \u00e9lectronique DC pour max. 150V, 40A, 200W. Avec interface USB Host, USB Device et RS232. Le r\u00e9seau local est disponible en option. <\/p>\n<hr>\n<h3>Pourquoi choisir le DL3021 ?<\/h3>\n<p>Le DL3021 est con\u00e7u pour offrir une fiabilit\u00e9 et une pr\u00e9cision in\u00e9gal\u00e9es dans les environnements les plus exigeants. Con\u00e7u pour les ing\u00e9nieurs qui privil\u00e9gient la performance, cet appareil garantit des r\u00e9sultats stables pour la R&#038;D, l&rsquo;assurance qualit\u00e9 et la maintenance industrielle. Contactez-nous d\u00e8s aujourd&rsquo;hui pour une assistance technique personnalis\u00e9e et des demandes de renseignements en vrac. <\/p>\n<p><a href=\"https:\/\/ccontrols.shop\/wp-content\/uploads\/2026\/05\/DL3000_DataSheet_EN_tcm30-3977.pdf\">DL3000_DataSheet_EN_tcm30-3977<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"custom-attribute-values-only\" style=\"font-size: 15px; font-weight: 500; line-height: 1.4; color: #333;\">Charge en courant continu, 200 W, 150 V, 40 A, 2.5 A\/us, CC, 4.3&Prime; TFT, LAN<\/div>\n","protected":false},"featured_media":60230,"comment_status":"closed","ping_status":"open","template":"","meta":{"content-type":""},"product_brand":[1971],"product_cat":[338],"product_tag":[],"class_list":["post-4653","product","type-product","status-publish","has-post-thumbnail","product_brand-rigol","product_cat-alimentations","pa_current-40-a","pa_display-4-3-tft","pa_interface-lan","pa_interface-usb","pa_modes-cc","pa_modes-cp","pa_modes-cr","pa_modes-cv","pa_power-6831","pa_power-type-charge-en-courant-continu","pa_power-unit-w","pa_slew-rate-2-5-a-us","pa_voltage-150-v","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author","","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"builder_content":"","_links":{"self":[{"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/product\/4653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/comments?post=4653"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/media\/60230"}],"wp:attachment":[{"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/media?parent=4653"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/product_brand?post=4653"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/product_cat?post=4653"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ccontrols.shop\/fr\/wp-json\/wp\/v2\/product_tag?post=4653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}