{"id":2795,"date":"2026-05-08T14:07:23","date_gmt":"2026-05-08T14:07:23","guid":{"rendered":"http:\/\/sokadohi.cyon.site\/produkt\/phu-200-70d\/"},"modified":"2026-07-15T15:32:28","modified_gmt":"2026-07-15T15:32:28","slug":"phu-200-70d","status":"publish","type":"product","link":"https:\/\/ccontrols.shop\/it\/product\/phu-200-70d\/","title":{"rendered":"PHU 200-70D"},"content":{"rendered":"<h1>GW INSTEK - PHU 200-70D&nbsp;<\/h1>\n<p>PHU 200-70D \u00e8 un alimentatore CC programmabile da 200 V, 70 A e 5000 W<\/p>\n<p>Prestige \/ Harmony \/ Universal<\/p>\n<p>La serie PHU \u00e8 un alimentatore CC programmabile a canale singolo con funzione di selezione automatica della gamma di uscita (multi-range), che offre un&#8217;ampia gamma di combinazioni di tensione e corrente per una maggiore flessibilit\u00e0. Il progetto del circuito utilizza componenti in SiC (carburo di silicio) per ottenere un&#8217;elevata densit\u00e0 di potenza, in grado di generare 15 kW di potenza in uscita mantenendo dimensioni compatte con un&#8217;altezza di soli 3U. <\/p>\n<p>L&#8217;ampio intervallo di tensione e corrente del PHU, insieme alle sue caratteristiche di alta potenza, permette di coprire una gamma pi\u00f9 ampia di applicazioni di collaudo, come i sistemi fotovoltaici, i veicoli elettrici (EV) e l&#8217;elettronica automobilistica, ecc. Il lancio della sorgente di corrente continua ad alta potenza con selezione automatica della gamma (multigamma) PHU arricchisce la gamma di alimentatori CC di GW Instek, offrendo ai clienti soluzioni pi\u00f9 complete e integrate. <\/p>\n<p><span style=\"letter-spacing:0px;\">La funzione AWS (Advanced Web Server) permette all&#8217;utente di gestire i dispositivi direttamente tramite un browser web, senza dover installare software o driver complicati. Questa funzionalit\u00e0 consente agli utenti di svolgere le attivit\u00e0 in modo pi\u00f9 efficiente, risparmiando tempo e aumentando la produttivit\u00e0. <\/span><\/p>\n<p><span style=\"letter-spacing:0px;\">L&#8217;esclusiva funzione APC (Adaptive Parallel Connection) offre flessibilit\u00e0 nel collegamento in parallelo, permettendo agli utenti di scegliere la soluzione pi\u00f9 adatta alle proprie esigenze. Ad esempio, puoi optare per un modello da 15 kW e uno da 10 kW e combinarli per raggiungere una potenza di 25 kW senza sforare il tuo budget. \u00c8 possibile collegare fino a 10 unit\u00e0 PHU per arrivare a 150 kW senza bisogno di una distribuzione di potenza aggiuntiva per il controllo. &nbsp;<\/span><\/p>\n<p><span style=\"letter-spacing:0px;\">Per quanto riguarda le interfacce industriali, PHU offre una vasta gamma di opzioni di interfacce industriali integrate per soddisfare le esigenze degli utenti, evitando loro di dover predisporre interfacce aggiuntive. Le porte disponibili includono EtherCAT, CANopen, Modbus, Profinet e DeviceNet, ecc. Oltre alla funzione standard integrata di sequenza programmabile, PHU offre anche una serie di funzioni opzionali, tra cui Datalogger, Capacit\u00e0\/Energia, Simulatore di pannelli solari e Simulazione della batteria, per soddisfare le esigenze dei clienti. <\/span><\/p>\n<p><span style=\"letter-spacing:0px;\">Ci sono in totale 18 modelli, disponibili in 3 potenze (5 kW\/10 kW\/15 kW) e 6 tensioni (80 V\/200 V\/500 V\/750 V\/1000 V\/1500 V) per soddisfare tutte le esigenze dei clienti.&nbsp;<\/span><\/p>\n<p><span style=\"letter-spacing:0px;\">Caratteristiche <br \/>- Tensione in uscita: 80 V \/ 200 V \/ 500 V \/ 750 V \/ 1000 V \/ 1500 V <br \/>- Potenza in uscita: 5 kW\/ 10 kW\/ 15 kW<br \/>- Corrente massima in uscita: 510 A<br \/>- Modalit\u00e0 prioritaria C.C.\/C.V.<br \/>- Tempi di salita e discesa di tensione\/corrente regolabili<br \/>- AWS (Advanced Web Control)<br \/>- APC (Adaptive Parallel Connection)<br \/>- Collegamento in parallelo (massimo 10 unit\u00e0)<br \/>- Alta efficienza e alta densit\u00e0 di potenza<br \/>- Funzione di controllo del bleeder<br \/>- Funzione di resistenza interna<br \/>- Funzione di blocco del pannello<br \/>- Tre set di funzioni preimpostate<br \/>- Protezioni: OVP, OCP, OHP, UVL, guasto CA, guasto ventola<br \/>- Standard: USB, LAN, controllo analogico isolato<br \/>- Opzioni: RS-232 e 485 oppure GPIB oppure CAN Bus oppure Device Net oppure qualsiasi bus<br \/>- Altezza 3U e formato per montaggio su rack da 19<\/span><\/p>\n<hr>\n<h3>Perch\u00e9 scegliere il PHU 200-70D?<\/h3>\n<p>Questo dispositivo \u00e8 stato progettato per soddisfare i pi\u00f9 elevati standard di precisione e affidabilit\u00e0 in ambienti particolarmente impegnativi. Che si tratti di ricerca e sviluppo, controllo qualit\u00e0 o collaudi di produzione, garantisce le prestazioni costanti su cui fanno affidamento i professionisti. Per consulenze tecniche e ulteriori dettagli, contatta oggi stesso il nostro team di esperti. <\/p>\n<p><a href=\"https:\/\/ccontrols.shop\/wp-content\/uploads\/2026\/05\/PHU-Series_Spec_20250304.pdf\">Specifiche serie PHU_20250304<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"custom-attribute-values-only\" style=\"font-size: 15px; font-weight: 500; line-height: 1.4; color: #333;\">Alta tensione, 200 V, 70 mA, 14000 W, 0.0001 Acc, &lt;2mVrms, Digitale, Nessuno<\/div>\n","protected":false},"featured_media":59615,"comment_status":"closed","ping_status":"open","template":"","meta":{"content-type":""},"product_brand":[1264],"product_cat":[274],"product_tag":[],"class_list":["post-2795","product","type-product","status-publish","has-post-thumbnail","product_brand-gw-instek","product_cat-alimentatori","pa_current-70-ma","pa_display-digitale","pa_interface-nessuno","pa_power-10973","pa_power-type-alta-tensione","pa_power-unit-w","pa_ripple-2mvrms","pa_voltage-200-v","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author","","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"builder_content":"","_links":{"self":[{"href":"https:\/\/ccontrols.shop\/it\/wp-json\/wp\/v2\/product\/2795","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccontrols.shop\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ccontrols.shop\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ccontrols.shop\/it\/wp-json\/wp\/v2\/comments?post=2795"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccontrols.shop\/it\/wp-json\/wp\/v2\/media\/59615"}],"wp:attachment":[{"href":"https:\/\/ccontrols.shop\/it\/wp-json\/wp\/v2\/media?parent=2795"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ccontrols.shop\/it\/wp-json\/wp\/v2\/product_brand?post=2795"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ccontrols.shop\/it\/wp-json\/wp\/v2\/product_cat?post=2795"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ccontrols.shop\/it\/wp-json\/wp\/v2\/product_tag?post=2795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}