{"id":3036,"date":"2026-05-08T14:14:01","date_gmt":"2026-05-08T14:14:01","guid":{"rendered":"http:\/\/sokadohi.cyon.site\/produkt\/it5101e\/"},"modified":"2026-07-15T15:34:18","modified_gmt":"2026-07-15T15:34:18","slug":"it5101e","status":"publish","type":"product","link":"https:\/\/ccontrols.shop\/it\/product\/it5101e\/","title":{"rendered":"IT5101E"},"content":{"rendered":"<h1><span style=\"font-weight:bold;\">ITECH - IT5101E - UNIT\u00c0 DEMO USATA<\/span><\/h1>\n<p><span style=\"font-weight:bold;\">IT5101E Tester per batterie<\/span><\/p>\n<p>La serie IT5100 \u00e8 una linea di tester per la resistenza interna delle batterie caratterizzati da elevata precisione, alta risoluzione e velocit\u00e0 elevata. L&#8217;IT5100 utilizza un sistema di rilevamento a 4 terminali in corrente alternata, il che significa che il tester pu\u00f2 misurare contemporaneamente la resistenza interna e la tensione con elevata precisione. La risoluzione della resistenza arriva fino a 0,1 \u00b5, mentre quella della tensione \u00e8 di 10 \u00b5V. &nbsp; In combinazione con un disco USB esterno, l&#8217;IT5100 permette di calcolare statistiche a lungo termine. Grazie alla funzione di comparatore integrata, l&#8217;IT5100 \u00e8 in grado di determinare automaticamente se i parametri delle batterie soddisfano gli standard e di calcolare la percentuale di conformit\u00e0, rendendolo adatto a una vasta gamma di test e selezione delle batterie. Interfaccia di comunicazione USB\/LAN integrata a supporto del protocollo SCPI. Una singola unit\u00e0 IT5102 supporta la misurazione di 16 canali di batterie; il collegamento master-slave arriva fino a un massimo di 17 set e il numero di canali di espansione pu\u00f2 raggiungere i 272, migliorando notevolmente l&#8217;efficienza dei test. Grazie all&#8217;interfaccia di comunicazione LAN\/RS232 integrata, la serie IT5100 trova ampia applicazione nell&#8217;ispezione e nella selezione di batterie al litio per cellulari, batterie per veicoli elettrici e altri tipi di batterie. <\/p>\n<p>Caratteristiche:<\/p>\n<ul>\n<li>Supporta il test e la visualizzazione simultanea di resistenza e tensione, schermo LCD da 4,3 pollici<\/li>\n<li>Intervalli di tensione: \u00b1300 V<\/li>\n<li>Intervalli di resistenza: da 15 m a 3000 m<\/li>\n<li>intervalli di tensione, 7 intervalli di resistenza, misurazione automatica o manuale a scelta<\/li>\n<li>Supporta il test simultaneo di resistenza e tensione, con una velocit\u00e0 fino a 125 volte al secondo in modalit\u00e0 Ex_Fast<\/li>\n<li>Interfacce USB e LAN integrate, supporta il protocollo SCPI.<\/li>\n<li>Calcolo delle statistiche e funzione di salvataggio dei dati su chiavetta USB<\/li>\n<li>Funzione di confronto: visualizzazione dei risultati dell&#8217;ordinamento HI\/IN\/LOW<\/li>\n<li>Funzione di regolazione dello zero<\/li>\n<li>Misura della corrente alternata a 4 terminali<\/li>\n<li>Allarme risultato della misurazione<\/li>\n<li>Disponibile per supportare la misurazione automatica del sistema di test di carica e scarica delle batterie ITS5300.&nbsp;<\/li>\n<\/ul>\n<hr>\n<h3>Perch\u00e9 scegliere l&#8217;IT5101E?<\/h3>\n<p>Questo dispositivo \u00e8 stato progettato per soddisfare i pi\u00f9 elevati standard di precisione e affidabilit\u00e0 in ambienti particolarmente impegnativi. Che si tratti di ricerca e sviluppo, controllo qualit\u00e0 o collaudi di produzione, garantisce le prestazioni costanti su cui fanno affidamento i professionisti. Per consulenze tecniche e ulteriori dettagli, contatta oggi stesso il nostro team di esperti. <\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"custom-attribute-values-only\" style=\"font-size: 15px; font-weight: 500; line-height: 1.4; color: #333;\">1 canale CH, 10, 10 \u00b5V, \u00b1300 V DC, Tensione: \u00b1(0, USB<\/div>\n","protected":false},"featured_media":59669,"comment_status":"closed","ping_status":"open","template":"","meta":{"content-type":""},"product_brand":[2928],"product_cat":[408],"product_tag":[],"class_list":["post-3036","product","type-product","status-publish","has-post-thumbnail","product_brand-itech","product_cat-metri","pa_resolution-digits-10-v","pa_resolution-meter-7026","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author","","first","instock","taxable","shipping-taxable","product-type-simple"],"builder_content":"","_links":{"self":[{"href":"https:\/\/ccontrols.shop\/it\/wp-json\/wp\/v2\/product\/3036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccontrols.shop\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ccontrols.shop\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ccontrols.shop\/it\/wp-json\/wp\/v2\/comments?post=3036"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccontrols.shop\/it\/wp-json\/wp\/v2\/media\/59669"}],"wp:attachment":[{"href":"https:\/\/ccontrols.shop\/it\/wp-json\/wp\/v2\/media?parent=3036"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ccontrols.shop\/it\/wp-json\/wp\/v2\/product_brand?post=3036"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ccontrols.shop\/it\/wp-json\/wp\/v2\/product_cat?post=3036"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ccontrols.shop\/it\/wp-json\/wp\/v2\/product_tag?post=3036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}