{"id":3102,"date":"2026-05-08T14:12:15","date_gmt":"2026-05-08T14:12:15","guid":{"rendered":"http:\/\/sokadohi.cyon.site\/produkt\/psw-160-21-6\/"},"modified":"2026-07-15T19:03:23","modified_gmt":"2026-07-15T19:03:23","slug":"psw-160-21-6","status":"publish","type":"product","link":"https:\/\/ccontrols.shop\/it\/product\/psw-160-21-6\/","title":{"rendered":"PSW 160-21,6"},"content":{"rendered":"<h1>GW INSTEK - PSW 160-21,6&nbsp;<\/h1>\n<p><span style=\"color:rgb(43,49,54);font-family:Inter, sans-serif;font-size:14px;font-style:normal;font-weight:500;letter-spacing:normal;text-indent:0px;text-transform:none;word-spacing:0px;white-space:normal;background-color:rgb(255,255,255);text-decoration-thickness:initial;text-decoration-style:initial;text-decoration-color:initial;float:none;\">- Alimentatore CC a commutazione programmabile a gamma multipla, 160 V, 21,6, 1080 W<\/span> &nbsp;<\/p>\n<p>La serie PSW \u00e8 una linea di alimentatori CC programmabili a commutazione, a uscita singola e a gamma multipla, che copre una potenza fino a 1080 W. Questa serie di prodotti comprende diciotto modelli con combinazioni di tensioni nominali da 30 V, 40 V, 80 V, 160 V, 250 V e 800 V e potenze di uscita massime da 360 W, 720 W e 1080 W. La funzione multigamma permette di configurare in modo flessibile ed efficiente tensione e corrente all&#8217;interno dell&#8217;intervallo di potenza nominale.<br \/>Poich\u00e9 la serie PSW pu\u00f2 essere collegata in serie (fino a un massimo di 2 unit\u00e0) o in parallelo (fino a un massimo di 3 unit\u00e0), la possibilit\u00e0 di collegare pi\u00f9 unit\u00e0 PSW per ottenere tensioni o correnti di uscita pi\u00f9 elevate garantisce un&#8217;ampia copertura di applicazioni. Grazie alla flessibilit\u00e0 nell&#8217;utilizzo della potenza a gamma multipla e al collegamento in serie\/parallelo, la serie PSW riduce significativamente l&#8217;investimento dell&#8217;utente in vari prodotti di alimentazione per soddisfare i progetti con requisiti di potenza diversi.<br \/>La selezione della priorit\u00e0 CV\/CC della serie PSW \u00e8 una funzione molto utile per la protezione del dispositivo in prova (DUT). Un alimentatore convenzionale di solito funziona in modalit\u00e0 CV quando si accende l&#8217;uscita di potenza. Questo potrebbe causare un&#8217;elevata corrente di spunto sul carico capacitivo o su un carico ad alto assorbimento di corrente nella fase di accensione dell&#8217;uscita. Prendiamo ad esempio la verifica della curva I-V di un LED: eseguire questa misurazione con un alimentatore convenzionale diventa un compito davvero impegnativo. Con il LED collegato a un alimentatore in modalit\u00e0 CV come impostazione iniziale, quando si accende l&#8217;uscita di potenza e la tensione sale fino alla tensione diretta del LED, la corrente raggiunge improvvisamente un picco e supera il valore preimpostato del limite di corrente. Rilevando questa corrente elevata, l&#8217;alimentatore avvia la transizione dalla modalit\u00e0 CV alla modalit\u00e0 CC.<br \/>Sebbene la corrente si stabilizzi dopo l&#8217;attivazione della modalit\u00e0 CC, il picco di corrente verificatosi nel punto di transizione tra CV e CC potrebbe danneggiare il dispositivo in prova (DUT). Nella fase di accensione dell&#8217;uscita di potenza, la serie PSW \u00e8 in grado di funzionare con priorit\u00e0 CC per limitare il picco di corrente che si verifica alla tensione di soglia e proteggere cos\u00ec il DUT dai danni causati dalla corrente di spunto. <\/p>\n<p> Caratteristiche:<br \/>- Tensione nominale: 30 V\/40 V\/80 V\/160 V\/250 V\/800 V, potenza di uscita nominale: 360 W ~ 1080 W<br \/>- Combinazioni multi-range di tensione e corrente in un unico alimentatore<br \/>- Priorit\u00e0 CV\/CC; Particolarmente adatto per il settore delle batterie e dei LED<br \/>- Velocit\u00e0 di risposta regolabile<br \/>- Funzionamento in serie (2 unit\u00e0 in serie) per (30 V\/40 V\/80 V\/160 V)<br \/>- Funzionamento in parallelo (fino a 3 unit\u00e0 in parallelo) per (30 V\/40 V\/80 V\/160 V\/250 V\/800 V)<br \/>- Alta efficienza e alta densit\u00e0 di potenza<br \/>- Design con dimensioni di montaggio su rack 1\/2, 1\/3, 1\/6 (standard EIA\/JIS) per 360 W, 720 W, 1080 W<br \/>- Interfacce standard: LAN, USB, interfaccia di controllo analogica<br \/>- Interfacce opzionali: adattatore GPIB-USB, cavo RS232-USB<br \/>- Driver LabView<\/p>\n<hr>\n<h3>Perch\u00e9 scegliere il PSW 160-21.6?<\/h3>\n<p>Questo dispositivo \u00e8 stato progettato per soddisfare i pi\u00f9 elevati standard di precisione e affidabilit\u00e0 in ambienti particolarmente impegnativi. Che si tratti di ricerca e sviluppo, controllo qualit\u00e0 o collaudi di produzione, garantisce le prestazioni costanti su cui fanno affidamento i professionisti. Per consulenze tecniche e ulteriori dettagli, contatta oggi stesso il nostro team di esperti. <\/p>\n<p><a href=\"https:\/\/ccontrols.shop\/wp-content\/uploads\/2026\/05\/BH_PSW-Series_E202208.pdf\">Serie BH_PSW_E202208<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"custom-attribute-values-only\" style=\"font-size: 15px; font-weight: 500; line-height: 1.4; color: #333;\">Multi-Range DC, 160 V, 21.6 A, 1080 W, 0.86, &lt;60mVpp, LAN, Supported<\/div>\n","protected":false},"featured_media":59660,"comment_status":"closed","ping_status":"open","template":"","meta":{"content-type":""},"product_brand":[1264],"product_cat":[274],"product_tag":[],"class_list":["post-3102","product","type-product","status-publish","has-post-thumbnail","product_brand-gw-instek","product_cat-alimentatori","pa_current-21-6-a","pa_efficiency-0-86","pa_interface-lan-usb","pa_power-6804","pa_power-type-multi-range-dc","pa_power-unit-w","pa_ripple-60mvpp","pa_series-para-supported","pa_voltage-160-v","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author","","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"builder_content":"","_links":{"self":[{"href":"https:\/\/ccontrols.shop\/it\/wp-json\/wp\/v2\/product\/3102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccontrols.shop\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ccontrols.shop\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ccontrols.shop\/it\/wp-json\/wp\/v2\/comments?post=3102"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccontrols.shop\/it\/wp-json\/wp\/v2\/media\/59660"}],"wp:attachment":[{"href":"https:\/\/ccontrols.shop\/it\/wp-json\/wp\/v2\/media?parent=3102"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ccontrols.shop\/it\/wp-json\/wp\/v2\/product_brand?post=3102"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ccontrols.shop\/it\/wp-json\/wp\/v2\/product_cat?post=3102"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ccontrols.shop\/it\/wp-json\/wp\/v2\/product_tag?post=3102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}