{"id":5189,"date":"2026-05-08T15:28:52","date_gmt":"2026-05-08T15:28:52","guid":{"rendered":"http:\/\/sokadohi.cyon.site\/produkt\/6014\/"},"modified":"2026-07-13T17:32:28","modified_gmt":"2026-07-13T17:32:28","slug":"6014","status":"publish","type":"product","link":"https:\/\/ccontrols.shop\/it\/product\/6014\/","title":{"rendered":"6014"},"content":{"rendered":"<\/p>\n<div class=\"magezon-builder magezon-builder-preload\">\n<div class=\"ggwh9d7 mgz-element mgz-element-row full_width_row\">\n<div class=\"mgz-element-inner ggwh9d7-s\">\n<div class=\"inner-content mgz-container\">\n<div class=\"mv4fvvb mgz-element mgz-element-column mgz-col-md-6\">\n<div class=\"mgz-element-inner mv4fvvb-s\">\n<div class=\"jvnrcqb mgz-element mgz-child mgz-element-text\">\n<div class=\"mgz-element-inner jvnrcqb-s\">\n<h1>Sensepeek - 6014&nbsp;<\/h1>\n<h3>- SQ200 - Sonda per oscilloscopio a mani libere da 200 MHz<\/h3>\n<p>La nuova serie di sonde a mani libere SQ di Sensepeek ha un punto di gravit\u00e0 pi\u00f9 basso che le rende ancora pi\u00f9 stabili rispetto alla serie originale SP di sonde a mani libere. Tutte le sonde della serie SQ sono inoltre isolate e possono essere utilizzate a mano come qualsiasi altra sonda tradizionale, ma il loro pieno potenziale viene sfruttato quando si misura a mani libere. <\/p>\n<p>La serie di sonde per oscilloscopio SQ include anche un maggior numero di opzioni di messa a terra, ha una protezione per la punta della sonda, un cavo pi\u00f9 lungo e supporta gli oscilloscopi con scalatura automatica (10:1) Tutte le amate caratteristiche di misurazione a mani libere, l&#8217;ago di prova con punta a molla a passo fine intercambiabile, i portacavi con codice colore e il design minimalista sono mantenuti per rendere obsolete le sonde palmari di dimensioni tradizionali. La lunghezza e il peso delle sonde SQ sono perfettamente bilanciati per essere utilizzati con i supporti PCBite e la piastra di base, indispensabili per la funzione handsfree. Per le specifiche tecniche, consulta il manuale d&#8217;uso. &nbsp;<\/p>\n<p>&nbsp;Include:&nbsp;<\/p>\n<p>&nbsp;1 sonda SQ200 200 MHz con ago di prova a molla&nbsp;<br \/><span style=\"letter-spacing:0px;\">&nbsp;1x Supporto per sonda SQ per misurare a mani libere&nbsp;<br \/><\/span><span style=\"letter-spacing:0px;\">&nbsp;1x Gancio di prova con cavi staccabili (5 cm e 10 cm) per un comodo collegamento a terra <br \/> 1x Cavo a coccodrillo per un comodo collegamento a terra <br \/> 1x Molla di terra standard, per misurazioni a mano libera con larghezza di banda nominale <br \/> 1x Molla di terra unica, per misurazioni a mano libera con larghezza di banda nominale <br \/> 1x Set di portacavi con codice colore (4 colori)&nbsp;<br \/><\/span><span style=\"letter-spacing:0px;\">&nbsp;1x Protezione della punta della sonda&nbsp;<br \/><\/span><span style=\"letter-spacing:0px;\">&nbsp;1x Ago di prova extra<\/span><span style=\"letter-spacing:0px;\"><br \/><\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"qe1mnag mgz-element mgz-element-column mgz-col-md-6 mgz-element-column-empty\">\n<div class=\"mgz-element-inner qe1mnag-s\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<hr>\n<h3>Perch\u00e9 scegliere il modello 6014?<\/h3>\n<p>Il 6014 \u00e8 costruito per offrire affidabilit\u00e0 e precisione senza pari negli ambienti pi\u00f9 difficili. Progettata per gli ingegneri che danno priorit\u00e0 alle prestazioni, questa unit\u00e0 garantisce risultati stabili per la ricerca e sviluppo, il controllo qualit\u00e0 e la manutenzione industriale. Contattaci oggi stesso per ricevere un&#8217;assistenza tecnica personalizzata e per richieste di informazioni su grandi quantit\u00e0. <\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":60750,"comment_status":"closed","ping_status":"open","template":"","meta":{"content-type":""},"product_brand":[5021],"product_cat":[633],"product_tag":[],"class_list":["post-5189","product","type-product","status-publish","has-post-thumbnail","product_brand-sensepeek","product_cat-accessori-2","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author","","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"builder_content":"","_links":{"self":[{"href":"https:\/\/ccontrols.shop\/it\/wp-json\/wp\/v2\/product\/5189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccontrols.shop\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ccontrols.shop\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ccontrols.shop\/it\/wp-json\/wp\/v2\/comments?post=5189"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccontrols.shop\/it\/wp-json\/wp\/v2\/media\/60750"}],"wp:attachment":[{"href":"https:\/\/ccontrols.shop\/it\/wp-json\/wp\/v2\/media?parent=5189"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ccontrols.shop\/it\/wp-json\/wp\/v2\/product_brand?post=5189"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ccontrols.shop\/it\/wp-json\/wp\/v2\/product_cat?post=5189"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ccontrols.shop\/it\/wp-json\/wp\/v2\/product_tag?post=5189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}